{"id":7029,"date":"2023-04-12T19:11:17","date_gmt":"2023-04-12T17:11:17","guid":{"rendered":"https:\/\/resisttoexist.de\/wp\/?p=7029"},"modified":"2023-04-20T09:00:57","modified_gmt":"2023-04-20T07:00:57","slug":"sinnfrei-beim-resist-to-exist-2023","status":"publish","type":"post","link":"https:\/\/resisttoexist.de\/wp\/en\/sinnfrei-beim-resist-to-exist-2023\/","title":{"rendered":"Sinnfrei beim Resist To Exist 2023!"},"content":{"rendered":"<p>Heute gibt es mal wieder was f\u00fcrs Tanzbein. Freut euch mit <a href=\"https:\/\/www.facebook.com\/sinnfreimusik?__cft__[0]=AZX9RY3dDCstnUzIVPjP4rdwjvlnod4AauvB0TrcrhVZ0x0c1B6wbmz1_D733zZnJ_j8K3K5cLpQyW4zPgoZ5UYOSCjKSVF3MtTEp7fL9d87_Ei-GWgcQVg7fIwiOChhVsI&amp;__tn__=-]K-R\">Sinnfrei<\/a> auf sch\u00f6nen Skapunk! <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sinnfrei - Um den freien Willen\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/wIs-TL9awh4?start=5&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"7030\" src=\"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-1024x1024.jpg\" alt=\"\" class=\"wp-image-7030\" srcset=\"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-1024x1024.jpg 1024w, https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-300x300.jpg 300w, https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-150x150.jpg 150w, https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-768x768.jpg 768w, https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-1536x1536.jpg 1536w, https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Heute gibt es mal wieder was f\u00fcrs Tanzbein. Freut euch mit Sinnfrei auf sch\u00f6nen Skapunk!<\/p>","protected":false},"author":8,"featured_media":7030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sinnfrei beim Resist To Exist 2023! - Resist to Exist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resisttoexist.de\/wp\/en\/sinnfrei-beim-resist-to-exist-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sinnfrei beim Resist To Exist 2023! - Resist to Exist\" \/>\n<meta property=\"og:description\" content=\"Heute gibt es mal wieder was f\u00fcrs Tanzbein. Freut euch mit Sinnfrei auf sch\u00f6nen Skapunk!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resisttoexist.de\/wp\/en\/sinnfrei-beim-resist-to-exist-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Resist to Exist\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T17:11:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T07:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-1024x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joerg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"joerg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/\"},\"author\":{\"name\":\"joerg\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#\\\/schema\\\/person\\\/92ee6e0e8f019ea01d994bb9e0148d06\"},\"headline\":\"Sinnfrei beim Resist To Exist 2023!\",\"datePublished\":\"2023-04-12T17:11:17+00:00\",\"dateModified\":\"2023-04-20T07:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/\"},\"wordCount\":33,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/2023-bands-sinnfrei.jpg\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/\",\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/\",\"name\":\"Sinnfrei beim Resist To Exist 2023! - Resist to Exist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/2023-bands-sinnfrei.jpg\",\"datePublished\":\"2023-04-12T17:11:17+00:00\",\"dateModified\":\"2023-04-20T07:00:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/2023-bands-sinnfrei.jpg\",\"contentUrl\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/2023-bands-sinnfrei.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/sinnfrei-beim-resist-to-exist-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sinnfrei beim Resist To Exist 2023!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/\",\"name\":\"Resist to Exist\",\"description\":\"02. \u2013 04. August 2024\",\"publisher\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#organization\",\"name\":\"Resist to Exist\",\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/rte-branding.png\",\"contentUrl\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/wp-content\\\/uploads\\\/rte-branding.png\",\"width\":1960,\"height\":360,\"caption\":\"Resist to Exist\"},\"image\":{\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/#\\\/schema\\\/person\\\/92ee6e0e8f019ea01d994bb9e0148d06\",\"name\":\"joerg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g\",\"caption\":\"joerg\"},\"url\":\"https:\\\/\\\/resisttoexist.de\\\/wp\\\/en\\\/author\\\/joerg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sinnfrei beim Resist To Exist 2023! - Resist to Exist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resisttoexist.de\/wp\/en\/sinnfrei-beim-resist-to-exist-2023\/","og_locale":"en_US","og_type":"article","og_title":"Sinnfrei beim Resist To Exist 2023! - Resist to Exist","og_description":"Heute gibt es mal wieder was f\u00fcrs Tanzbein. Freut euch mit Sinnfrei auf sch\u00f6nen Skapunk!","og_url":"https:\/\/resisttoexist.de\/wp\/en\/sinnfrei-beim-resist-to-exist-2023\/","og_site_name":"Resist to Exist","article_published_time":"2023-04-12T17:11:17+00:00","article_modified_time":"2023-04-20T07:00:57+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei-1024x1024.jpg","type":"image\/jpeg"}],"author":"joerg","twitter_misc":{"Written by":"joerg"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#article","isPartOf":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/"},"author":{"name":"joerg","@id":"https:\/\/resisttoexist.de\/wp\/#\/schema\/person\/92ee6e0e8f019ea01d994bb9e0148d06"},"headline":"Sinnfrei beim Resist To Exist 2023!","datePublished":"2023-04-12T17:11:17+00:00","dateModified":"2023-04-20T07:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/"},"wordCount":33,"commentCount":0,"publisher":{"@id":"https:\/\/resisttoexist.de\/wp\/#organization"},"image":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei.jpg","articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/","url":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/","name":"Sinnfrei beim Resist To Exist 2023! - Resist to Exist","isPartOf":{"@id":"https:\/\/resisttoexist.de\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#primaryimage"},"image":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei.jpg","datePublished":"2023-04-12T17:11:17+00:00","dateModified":"2023-04-20T07:00:57+00:00","breadcrumb":{"@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#primaryimage","url":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei.jpg","contentUrl":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/2023-bands-sinnfrei.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/resisttoexist.de\/wp\/sinnfrei-beim-resist-to-exist-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/resisttoexist.de\/wp\/"},{"@type":"ListItem","position":2,"name":"Sinnfrei beim Resist To Exist 2023!"}]},{"@type":"WebSite","@id":"https:\/\/resisttoexist.de\/wp\/#website","url":"https:\/\/resisttoexist.de\/wp\/","name":"Resist to Exist","description":"02. \u2013 04. August 2024","publisher":{"@id":"https:\/\/resisttoexist.de\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resisttoexist.de\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/resisttoexist.de\/wp\/#organization","name":"Resist to Exist","url":"https:\/\/resisttoexist.de\/wp\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/resisttoexist.de\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/rte-branding.png","contentUrl":"https:\/\/resisttoexist.de\/wp\/wp-content\/uploads\/rte-branding.png","width":1960,"height":360,"caption":"Resist to Exist"},"image":{"@id":"https:\/\/resisttoexist.de\/wp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/resisttoexist.de\/wp\/#\/schema\/person\/92ee6e0e8f019ea01d994bb9e0148d06","name":"joerg","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2154026125cc2c609ea51ee75a150423ae9e2a1781deb85f2926288335cf4399?s=96&d=mm&r=g","caption":"joerg"},"url":"https:\/\/resisttoexist.de\/wp\/en\/author\/joerg\/"}]}},"_links":{"self":[{"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/posts\/7029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/comments?post=7029"}],"version-history":[{"count":2,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/posts\/7029\/revisions"}],"predecessor-version":[{"id":7032,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/posts\/7029\/revisions\/7032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/media\/7030"}],"wp:attachment":[{"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/media?parent=7029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/categories?post=7029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resisttoexist.de\/wp\/en\/wp-json\/wp\/v2\/tags?post=7029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}